{"id":5005,"date":"2025-05-20T11:10:18","date_gmt":"2025-05-20T09:10:18","guid":{"rendered":"https:\/\/www.cislferrara.it\/?p=5005"},"modified":"2025-05-20T11:10:18","modified_gmt":"2025-05-20T09:10:18","slug":"i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza","status":"publish","type":"post","link":"https:\/\/www.cislferrara.it\/fr\/i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza\/","title":{"rendered":"Les n\u0153uds du d\u00e9veloppement : \u00ab Nous avons besoin d\u2019un nouveau pacte entre ceux qui produisent la richesse \u00bb"},"content":{"rendered":"<h6 style=\"text-align: center;\">Le secr\u00e9taire de la CISL, Tagliavia, r\u00e9it\u00e8re la proposition faite ces derniers jours : \u00ab Infrastructures, l&#039;attention du gouvernement est la bienvenue. Revitalisation, les travailleurs comme protagonistes. \u00bb<\/h6>\n<h6><a href=\"https:\/\/www.cislferrara.it\/wp-content\/uploads\/2025\/05\/i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5006 aligncenter\" src=\"https:\/\/www.cislferrara.it\/wp-content\/uploads\/2025\/05\/i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza-300x169.jpg\" alt=\"\" width=\"337\" height=\"190\" srcset=\"https:\/\/www.cislferrara.it\/wp-content\/uploads\/2025\/05\/i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza-300x169.jpg 300w, https:\/\/www.cislferrara.it\/wp-content\/uploads\/2025\/05\/i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza-18x10.jpg 18w, https:\/\/www.cislferrara.it\/wp-content\/uploads\/2025\/05\/i-nodi-dello-sviluppo-occorre-un-nuovo-patto-tra-chi-produce-ricchezza.jpg 580w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/a><\/h6>\n<p style=\"text-align: center;\">Les nouvelles fournies par le sous-secr\u00e9taire aux infrastructures nous donnent de l\u2019espoir,\u00a0<strong>Tullio Ferrante<\/strong>, ce qui a permis \u00e0 l&#039;ex\u00e9cutif d&#039;accorder son attention \u00e0 certaines des\u00a0<strong>carrefours routiers les plus strat\u00e9giques<\/strong>\u00a0pour notre territoire. Il est clair que, dans un contexte \u00e9conomique et social comme celui de Ferrare, mettre en lumi\u00e8re le p\u00f4le d&#039;infrastructures implique n\u00e9cessairement de se projeter vers l&#039;avenir et d&#039;imaginer un renforcement de la\u00a0<strong>comp\u00e9titivit\u00e9<\/strong>\u00a0Pour notre monde productif. Plus de stabilit\u00e9, plus de comp\u00e9titivit\u00e9, plus de perspectives pour nos entreprises \u2013 petites, moyennes ou grandes \u2013 se traduisent par des emplois, une s\u00e9curit\u00e9 d&#039;emploi et une stabilit\u00e9 salariale. \u00c0 cet \u00e9gard, les donn\u00e9es fournies par Carlino ces derniers jours concernant<strong>acc\u00e8s au cr\u00e9dit<\/strong>\u00a0pour le secteur productif de notre province. Le rapport met en lumi\u00e8re une situation extr\u00eamement difficile, o\u00f9 les versements des \u00e9tablissements de cr\u00e9dit aux entreprises productives diminuent progressivement et r\u00e9guli\u00e8rement depuis des ann\u00e9es. Ce facteur, loin d&#039;\u00eatre secondaire, impacte les perspectives de ceux qui souhaitent investir dans la r\u00e9gion. Pour cette raison, et bien d&#039;autres, je trouve int\u00e9ressante la proposition formul\u00e9e par le secr\u00e9taire provincial de Confartigianato, Paolo Cirelli, dans les colonnes de ce journal, et je me sens en mesure de la soutenir. D&#039;autant plus qu&#039;elle renvoie \u00e0 une bataille historique.\u00a0<strong>CISL<\/strong>: celui de la\u00a0<strong>pacte social<\/strong>Il est donc n\u00e9cessaire de conclure un pacte entre les producteurs de richesses de cette r\u00e9gion, inspir\u00e9 par ces principes, notamment au vu des donn\u00e9es micro et macro\u00e9conomiques pr\u00e9occupantes. Je crois que ce \u00ab\u00a0pacte\u00a0\u00bb doit \u00eatre pleinement soutenu par les diff\u00e9rents acteurs de la cha\u00eene de production, \u00e0 commencer par les syndicats et les repr\u00e9sentants des travailleurs. En fin de compte, par les travailleurs eux-m\u00eames.<\/p>\n<div class=\"OB-REACT-WRAPPER\">\n<div class=\"OUTBRAIN\" data-src=\"https:\/\/www.ilrestodelcarlino.it\/ferrara\/cronaca\/i-nodi-dello-sviluppo-occorre-d280d034\" data-widget-id=\"AR_2\"><\/div>\n<\/div>\n<p style=\"text-align: center;\">La direction que nous devons prendre est pr\u00e9cis\u00e9ment celle du travail d&#039;\u00e9quipe visant \u00e0 inverser la tendance au d\u00e9clin dans ce domaine, en avan\u00e7ant ensemble. La CISL est pr\u00eate \u00e0 apporter sa contribution \u00e0 cet \u00e9gard, fid\u00e8le \u00e0 une valeur \u00e0 laquelle nous croyons profond\u00e9ment\u00a0: la participation. C&#039;est pr\u00e9cis\u00e9ment l&#039;objectif du travail men\u00e9 par notre secr\u00e9tariat au niveau national, qui conduit \u00e0 l&#039;approbation d&#039;une loi sur la participation des travailleurs \u00e0 la gouvernance des entreprises. Notre province a besoin d&#039;interventions exceptionnelles et d&#039;une nouvelle approche de ces questions, plus int\u00e9gr\u00e9e, plus structurelle, et qui rompe avec les anciennes approches conflictuelles. Les partenaires sociaux doivent apporter leur contribution, car les travailleurs \u2013 le peuple \u2013 doivent \u00eatre au c\u0153ur de la vie \u00e9conomique de cette r\u00e9gion.<\/p>\n<p><a href=\"https:\/\/www.ilrestodelcarlino.it\/ferrara\/cronaca\/i-nodi-dello-sviluppo-occorre-d280d034\">Lire l&#039;article sur Resto del Carlino<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le secr\u00e9taire d&#039;\u00c9tat \u00e0 la CISL, M. Tagliavia, r\u00e9it\u00e8re la proposition formul\u00e9e ces derniers jours\u00a0: \u201c\u00a0L&#039;attention du gouvernement est la bienvenue concernant les infrastructures. Il faut redynamiser le secteur et placer les travailleurs au c\u0153ur du projet.\u00a0\u201d Les nouvelles communiqu\u00e9es par le sous-secr\u00e9taire d&#039;\u00c9tat aux Infrastructures, M. Tullio Ferrante, sont encourageantes\u2026<\/p>","protected":false},"author":6,"featured_media":5006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,25],"tags":[450,66,452,451,143],"class_list":{"0":"post-5005","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cisl-ferrara","8":"category-parola-al-segretario","9":"tag-infrastrutture","10":"tag-lavoratori","11":"tag-protagonisti","12":"tag-rilancio","13":"tag-tagliavia"},"_links":{"self":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts\/5005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/comments?post=5005"}],"version-history":[{"count":1,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts\/5005\/revisions"}],"predecessor-version":[{"id":5007,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts\/5005\/revisions\/5007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/media\/5006"}],"wp:attachment":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/media?parent=5005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/categories?post=5005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/tags?post=5005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}