{"id":3234,"date":"2019-08-28T11:07:18","date_gmt":"2019-08-28T09:07:18","guid":{"rendered":"https:\/\/www.cislferrara.it\/?p=3234"},"modified":"2019-08-28T11:13:49","modified_gmt":"2019-08-28T09:13:49","slug":"fiaccolata-contro-il-femminicidio","status":"publish","type":"post","link":"https:\/\/www.cislferrara.it\/fr\/fiaccolata-contro-il-femminicidio\/","title":{"rendered":"Marche aux flambeaux contre le f\u00e9minicide"},"content":{"rendered":"<p>Dans le dictionnaire italien, la d\u00e9finition du terme f\u00e9minicide est la suivante :<\/p>\n<p>\u00ab Toute forme de violence exerc\u00e9e syst\u00e9matiquement contre les femmes au nom d\u2019une superstructure id\u00e9ologique patriarcale, dans le but de perp\u00e9tuer leur subordination et d\u2019annihiler leur identit\u00e9 par l\u2019assujettissement physique ou psychologique, pouvant aller jusqu\u2019\u00e0 l\u2019esclavage ou la mort. \u00bb<\/p>\n<p>En quelques mots \u00ab Tuer une femme ou une fille \u00bb. Nous, les femmes, continuons \u00e0 mourir aux mains des hommes. \u00c0 cause de la haine, parce qu\u2019ils ne peuvent pas accepter la fin d\u2019une histoire d\u2019amour, parce qu\u2019ils ne connaissent pas le sens du \u00ab non \u00bb.<\/p>\n<p>Une procession aux flambeaux pour Cinzia et pour toutes les femmes qui aujourd&#039;hui sont victimes de violence silencieuse, pour qu&#039;elles sachent qu&#039;elles ne sont pas et ne seront jamais seules, car nous serons toujours l\u00e0 pour les soutenir, car nous lutterons toujours \u00e0 leurs c\u00f4t\u00e9s.<\/p>\n<p>Jusqu&#039;au jour o\u00f9 chaque homme comprendra qu&#039;une femme est une personne libre de penser, libre de faire des choix, libre de vivre.<\/p>\n<p>Le Secr\u00e9taire G\u00e9n\u00e9ral UST-CISL Ferrara<\/p>\n<p>Barberis brun<\/p>\n<p>&nbsp;<\/p>\n<p>T\u00e9l\u00e9charger ici \u2013&gt; <a href=\"https:\/\/www.cislferrara.it\/wp-content\/uploads\/2019\/08\/locandina-29-agosto.pdf\">affiche de procession aux flambeaux contre le f\u00e9minicide<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp; <\/p>","protected":false},"excerpt":{"rendered":"<p>Nel dizionario della lingua italiana, alla definizione del termine femminicidio si legge cos\u00ec: \u201cQualsiasi forma di violenza esercitata sistematicamente sulle donne in nome di una sovrastruttura ideologica di matrice patriarcale,&#8230;<\/p>","protected":false},"author":3,"featured_media":3235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19],"tags":[],"class_list":{"0":"post-3234","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-area-stampa","8":"category-cisl-ferrara"},"_links":{"self":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts\/3234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/comments?post=3234"}],"version-history":[{"count":0,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/posts\/3234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/media\/3235"}],"wp:attachment":[{"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/media?parent=3234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/categories?post=3234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cislferrara.it\/fr\/wp-json\/wp\/v2\/tags?post=3234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}